{"id":9347,"count":56,"description":"","link":"https:\/\/allfoodonline.com\/en\/category\/bakery\/","name":"Bakery","slug":"bakery","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bakery Archivi - Allfoodonline<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/allfoodonline.com\/en\/category\/bakery\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bakery Archivi - Allfoodonline\" \/>\n<meta property=\"og:url\" content=\"https:\/\/allfoodonline.com\/en\/category\/bakery\/\" \/>\n<meta property=\"og:site_name\" content=\"Allfoodonline\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/allfoodonline.com\\\/en\\\/category\\\/bakery\\\/\",\"url\":\"https:\\\/\\\/allfoodonline.com\\\/en\\\/category\\\/bakery\\\/\",\"name\":\"Bakery Archivi - Allfoodonline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/allfoodonline.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/allfoodonline.com\\\/en\\\/category\\\/bakery\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/allfoodonline.com\\\/en\\\/category\\\/bakery\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/allfoodonline.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bakery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/allfoodonline.com\\\/#website\",\"url\":\"https:\\\/\\\/allfoodonline.com\\\/\",\"name\":\"Allfoodonline\",\"description\":\"il portale del prodotto alimentare e delle bevande\",\"publisher\":{\"@id\":\"https:\\\/\\\/allfoodonline.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/allfoodonline.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/allfoodonline.com\\\/#organization\",\"name\":\"Allfoodonline\",\"url\":\"https:\\\/\\\/allfoodonline.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/allfoodonline.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/allfoodonline.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-allfoodonline-logo.png\",\"contentUrl\":\"https:\\\/\\\/allfoodonline.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-allfoodonline-logo.png\",\"width\":252,\"height\":70,\"caption\":\"Allfoodonline\"},\"image\":{\"@id\":\"https:\\\/\\\/allfoodonline.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bakery Archivi - Allfoodonline","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/allfoodonline.com\/en\/category\/bakery\/","og_locale":"en_US","og_type":"article","og_title":"Bakery Archivi - Allfoodonline","og_url":"https:\/\/allfoodonline.com\/en\/category\/bakery\/","og_site_name":"Allfoodonline","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/allfoodonline.com\/en\/category\/bakery\/","url":"https:\/\/allfoodonline.com\/en\/category\/bakery\/","name":"Bakery Archivi - Allfoodonline","isPartOf":{"@id":"https:\/\/allfoodonline.com\/#website"},"breadcrumb":{"@id":"https:\/\/allfoodonline.com\/en\/category\/bakery\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/allfoodonline.com\/en\/category\/bakery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/allfoodonline.com\/en\/"},{"@type":"ListItem","position":2,"name":"Bakery"}]},{"@type":"WebSite","@id":"https:\/\/allfoodonline.com\/#website","url":"https:\/\/allfoodonline.com\/","name":"Allfoodonline","description":"il portale del prodotto alimentare e delle bevande","publisher":{"@id":"https:\/\/allfoodonline.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/allfoodonline.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/allfoodonline.com\/#organization","name":"Allfoodonline","url":"https:\/\/allfoodonline.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/allfoodonline.com\/#\/schema\/logo\/image\/","url":"https:\/\/allfoodonline.com\/wp-content\/uploads\/2020\/11\/cropped-allfoodonline-logo.png","contentUrl":"https:\/\/allfoodonline.com\/wp-content\/uploads\/2020\/11\/cropped-allfoodonline-logo.png","width":252,"height":70,"caption":"Allfoodonline"},"image":{"@id":"https:\/\/allfoodonline.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/allfoodonline.com\/en\/wp-json\/wp\/v2\/categories\/9347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allfoodonline.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/allfoodonline.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/allfoodonline.com\/en\/wp-json\/wp\/v2\/posts?categories=9347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}